{"id":4048,"date":"2010-11-30T17:02:11","date_gmt":"2010-11-30T17:02:11","guid":{"rendered":"http:\/\/www.bv-guimaraes.org\/site\/?p=4048"},"modified":"2010-11-30T17:07:32","modified_gmt":"2010-11-30T17:07:32","slug":"pinheiro-2010-com-o-dobro-das-intoxicacoes-em-relacao-a-2009","status":"publish","type":"post","link":"https:\/\/www.bv-guimaraes.org\/site\/pinheiro-2010-com-o-dobro-das-intoxicacoes-em-relacao-a-2009\/","title":{"rendered":"Pinheiro 2010 com o dobro das intoxica\u00e7\u00f5es em rela\u00e7\u00e3o a 2009"},"content":{"rendered":"<p><a href=\"http:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/Pinheiro2010.jpg\" data-rel=\"lightbox-gallery-l12ypcT1\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4049  alignleft\" title=\"\" src=\"http:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/Pinheiro2010.jpg\" alt=\"\" width=\"266\" height=\"158\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">O n\u00famero de intoxica\u00e7\u00f5es por <strong>\u00e1lcool<\/strong>, registadas pelos Bombeiros Volunt\u00e1rios de Guimar\u00e3es, subiu em rela\u00e7\u00e3o ao ano passado.<\/p>\n<p style=\"text-align: justify;\">A estat\u00edstica, em compara\u00e7\u00e3o com a m\u00e9dia de 2009, reflecte um aumento na ordem dos 100%, tendo em conta que foram contabilizados <strong>23 casos<\/strong>, em contraste com as 12 ocorr\u00eancias verificadas no ano transacto.<\/p>\n<p style=\"text-align: justify;\">Este ano, os <strong>Bombeiros Volunt\u00e1rios de Guimar\u00e3es<\/strong> transportaram para Centro Hospitalar Alto Ave &#8211; Unidade de Guimar\u00e3es, 17 homens e 6 mulheres, enquanto no \u00faltimo ano houve o transporte de 11 homens e de uma mulher.<\/p>\n<p style=\"text-align: justify;\">Entre as 20 horas e a meia noite de segunda-feira, apenas duas pessoas foram socorridas, em contraste com a madrugada de ter\u00e7a-feira, em que, a partir das 00:00 horas, o ritmo de pedidos de ajuda aumentou significativamente e atingiu o auge entre a 1 e as 3 horas da madrugada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O n\u00famero de intoxica\u00e7\u00f5es por \u00e1lcool, registadas pelos Bombeiros Volunt\u00e1rios de Guimar\u00e3es, subiu em rela\u00e7\u00e3o ao ano passado. A estat\u00edstica, em compara\u00e7\u00e3o com a m\u00e9dia de 2009, reflecte um aumento na ordem dos 100%, tendo em conta que foram contabilizados<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[325,372,18,106,371,127,28],"class_list":["post-4048","post","type-post","status-publish","format-standard","hentry","category-noticias-gerais","tag-325","tag-alcool","tag-bombeiros-voluntarios-de-guimaraes","tag-centro-hospitalar-alto-ave","tag-intoxicacoes","tag-ocorrencias","tag-pinheiro"],"_links":{"self":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts\/4048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/comments?post=4048"}],"version-history":[{"count":7,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts\/4048\/revisions"}],"predecessor-version":[{"id":4055,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts\/4048\/revisions\/4055"}],"wp:attachment":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/media?parent=4048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/categories?post=4048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/tags?post=4048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}