{"id":4492,"date":"2011-03-04T15:32:45","date_gmt":"2011-03-04T15:32:45","guid":{"rendered":"http:\/\/www.bv-guimaraes.org\/site\/?p=4492"},"modified":"2011-03-04T15:32:45","modified_gmt":"2011-03-04T15:32:45","slug":"acidente-em-selho-s-lourenco-provoca-um-ferido","status":"publish","type":"post","link":"https:\/\/www.bv-guimaraes.org\/site\/acidente-em-selho-s-lourenco-provoca-um-ferido\/","title":{"rendered":"Acidente em Selho S. Louren\u00e7o provoca um ferido"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/acidente111.jpg\" data-rel=\"lightbox-gallery-1VIbhpdm\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-747\" title=\"\" src=\"http:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/acidente111.jpg\" alt=\"\" width=\"204\" height=\"127\" \/><\/a>Um ferido ligeiro \u00e9 o resultado de uma <strong>colis\u00e3o<\/strong> entre um ve\u00edculo ligeiro de passageiros e um ligeiro de mercadorias, ao in\u00edcio desta tarde, dia 4, na Rua Ant\u00f3nio Gomes Marinho, freguesia de <strong>Selho S. Louren\u00e7o<\/strong>.<br \/>\nO alerta foi dado pelas 12:51, tendo sido accionado para o local uma ambul\u00e2ncia, um ve\u00edculo de desencarceramento e seis bombeiros, tendo ainda contado com o apoio da VMER do Centro Hospitalar Alto Ave.<br \/>\nDada a viol\u00eancia do embate, foi necess\u00e1rio utilizar material de desencarceramento de modo a proceder a uma extrac\u00e7\u00e3o controlada da v\u00edtima.<br \/>\nA v\u00edtima, um homem de 34 anos, ap\u00f3s estabilizado no local foi transportada para o Centro Hospitalar Alto Ave \u2013 Unidade de Guimar\u00e3es.<br \/>\nNo local esteve ainda a GNR que condicionou a circula\u00e7\u00e3o autom\u00f3vel durante as opera\u00e7\u00f5es de socorro que duraram at\u00e9 \u00e0s 14:20.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um ferido ligeiro \u00e9 o resultado de uma colis\u00e3o entre um ve\u00edculo ligeiro de passageiros e um ligeiro de mercadorias, ao in\u00edcio desta tarde, dia 4, na Rua Ant\u00f3nio Gomes Marinho, freguesia de Selho S. Louren\u00e7o. O alerta foi dado<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[18,34,91,373,216,80,374,116],"class_list":["post-4492","post","type-post","status-publish","format-standard","hentry","category-noticias-gerais","tag-bombeiros-voluntarios-de-guimaraes","tag-colisao","tag-desencarceramento","tag-ferido-ligeiro","tag-gnr","tag-selho-s-lourenco","tag-veiculo-ligeiro","tag-vmer"],"_links":{"self":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts\/4492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/comments?post=4492"}],"version-history":[{"count":7,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts\/4492\/revisions"}],"predecessor-version":[{"id":4499,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts\/4492\/revisions\/4499"}],"wp:attachment":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/media?parent=4492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/categories?post=4492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/tags?post=4492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}