{"id":4838,"date":"2011-06-05T14:30:09","date_gmt":"2011-06-05T14:30:09","guid":{"rendered":"http:\/\/www.bv-guimaraes.org\/site\/?p=4838"},"modified":"2011-06-05T14:30:09","modified_gmt":"2011-06-05T14:30:09","slug":"tres-feridos-num-despiste-na-a11","status":"publish","type":"post","link":"https:\/\/www.bv-guimaraes.org\/site\/tres-feridos-num-despiste-na-a11\/","title":{"rendered":"Tr\u00eas feridos num despiste na A11"},"content":{"rendered":"<figure id=\"attachment_4202\" aria-describedby=\"caption-attachment-4202\" style=\"width: 202px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/acidente6.jpg\" data-rel=\"lightbox-gallery-rP61OQqQ\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-4202\" title=\"\" src=\"http:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/acidente6.jpg\" alt=\"\" width=\"202\" height=\"135\" srcset=\"https:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/acidente6.jpg 554w, https:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/acidente6-300x199.jpg 300w\" sizes=\"auto, (max-width: 202px) 100vw, 202px\" \/><\/a><figcaption id=\"caption-attachment-4202\" class=\"wp-caption-text\">Foto de Arquivo<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ao final da tarde de ontem, dia 4, uma colis\u00e3o entre dois ve\u00edculos ligeiros de passageiros, na auto-estrada <strong>A11<\/strong>, sentido Guimar\u00e3es \u2013 Braga, ao km 35 que fica situado na freguesia de Figueiredo, provocou tr\u00eas feridos.<br \/>\nO alerta foi dado pelas 17:13, tendo sido accionado para o local tr\u00eas ambul\u00e2ncias e um ve\u00edculo de desencarceramento com um total de quinze bombeiros, j\u00e1 que havia a informa\u00e7\u00e3o de haver v\u00edtimas encarceradas.<br \/>\nJ\u00e1 no local, confirmou-se que duas das tr\u00eas v\u00edtimas se encontravam encarceradas pelo que foi necess\u00e1rio utilizar material de desencarceramento de modo a proceder a uma extrac\u00e7\u00e3o controlada das mesmas. Ap\u00f3s extrac\u00e7\u00e3o e estabiliza\u00e7\u00e3o das v\u00edtimas, as tr\u00eas mulheres de 27, 48 e 50 anos foram transportadas para o Hospital de Braga. No local esteve ainda a VMER de Guimar\u00e3es e a GNR-BT que condicionou o tr\u00e2nsito numa das vias da auto-estrada durante as opera\u00e7\u00f5es de socorro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao final da tarde de ontem, dia 4, uma colis\u00e3o entre dois ve\u00edculos ligeiros de passageiros, na auto-estrada A11, sentido Guimar\u00e3es \u2013 Braga, ao km 35 que fica situado na freguesia de Figueiredo, provocou tr\u00eas feridos. O alerta foi dado<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[392,142,18,34,294,47,383],"class_list":["post-4838","post","type-post","status-publish","format-standard","hentry","category-noticias-gerais","tag-a11","tag-auto-estrada","tag-bombeiros-voluntarios-de-guimaraes","tag-colisao","tag-encarceradas","tag-feridos","tag-vitimas"],"_links":{"self":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts\/4838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/comments?post=4838"}],"version-history":[{"count":5,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts\/4838\/revisions"}],"predecessor-version":[{"id":6478,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts\/4838\/revisions\/6478"}],"wp:attachment":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/media?parent=4838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/categories?post=4838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/tags?post=4838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}