{"id":5974,"date":"2012-10-22T09:22:05","date_gmt":"2012-10-22T09:22:05","guid":{"rendered":"http:\/\/www.bv-guimaraes.org\/site\/?p=5974"},"modified":"2012-10-22T22:08:52","modified_gmt":"2012-10-22T22:08:52","slug":"convivio-de-operadores-de-central-do-distrito-de-braga-2","status":"publish","type":"post","link":"https:\/\/www.bv-guimaraes.org\/site\/convivio-de-operadores-de-central-do-distrito-de-braga-2\/","title":{"rendered":"Conv\u00edvio de Operadores de Central do Distrito de Braga"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/bolo-conv\u00edvio.jpg\" data-rel=\"lightbox-gallery-V0JGQahh\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-5975\" title=\"\" src=\"http:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/bolo-conv\u00edvio-300x225.jpg\" alt=\"\" width=\"227\" height=\"171\" srcset=\"https:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/bolo-conv\u00edvio-300x225.jpg 300w, https:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/bolo-conv\u00edvio.jpg 960w\" sizes=\"auto, (max-width: 227px) 100vw, 227px\" \/><\/a>Realizou-se no passado dia 20 de Outubro em Vieira do Minho, o j\u00e1 tradicional conv\u00edvio dos Operadores de Central do Distrito de Braga.<br \/>\nA organiza\u00e7\u00e3o deste 9\u00ba conv\u00edvio esteve a cargo dos Bombeiros Volunt\u00e1rios Vieira do Minho que proporcionou nas instala\u00e7\u00f5es do clube de tiro local uma tarde com diversos jogos de equipa fomentando a intere\u00e7\u00e3o de todos os participantes. Enquanto uns \u00edam jogando, outros conviviam e aqueciam-se \u00e0 volta de um porco no espeto j\u00e1 que nesta altura do ano o frio j\u00e1 se nota bastante na Serra da Cabreira. No final seguiu-se o tradicional jantar e consequentemente entrega de lembran\u00e7as.<br \/>\nOs Bombeiros Volunt\u00e1rios de Guimar\u00e3es, fizeram-se representar por tr\u00eas bombeiros.<br \/>\nA t\u00edtulo de curiosidade o 10\u00ba conv\u00edvio a realizar-se no pr\u00f3ximo ano, estar\u00e1 a cargo dos Bombeiros Volunt\u00e1rios de Barcelos.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/conv\u00edvio.jpg\" data-rel=\"lightbox-gallery-V0JGQahh\" data-rl_title=\"\" data-rl_caption=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5992\" title=\"\" src=\"http:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/conv\u00edvio.jpg\" alt=\"\" width=\"590\" height=\"400\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Realizou-se no passado dia 20 de Outubro em Vieira do Minho, o j\u00e1 tradicional conv\u00edvio dos Operadores de Central do Distrito de Braga. A organiza\u00e7\u00e3o deste 9\u00ba conv\u00edvio esteve a cargo dos Bombeiros Volunt\u00e1rios Vieira do Minho que proporcionou nas<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3],"tags":[18,62,156],"class_list":["post-5974","post","type-post","status-publish","format-standard","hentry","category-noticias-quartel","tag-bombeiros-voluntarios-de-guimaraes","tag-convivio","tag-operador-de-central"],"_links":{"self":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts\/5974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/comments?post=5974"}],"version-history":[{"count":10,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts\/5974\/revisions"}],"predecessor-version":[{"id":5993,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts\/5974\/revisions\/5993"}],"wp:attachment":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/media?parent=5974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/categories?post=5974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/tags?post=5974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}