{"id":6829,"date":"2014-09-14T21:44:54","date_gmt":"2014-09-14T21:44:54","guid":{"rendered":"http:\/\/www.bv-guimaraes.org\/site\/?p=6829"},"modified":"2014-09-14T21:44:54","modified_gmt":"2014-09-14T21:44:54","slug":"acidente-choque-em-cadeia-provoca-quatro-feridos","status":"publish","type":"post","link":"https:\/\/www.bv-guimaraes.org\/site\/acidente-choque-em-cadeia-provoca-quatro-feridos\/","title":{"rendered":"ACIDENTE | Choque em cadeia provoca quatro feridos"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"http:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/acidente6.jpg\" data-rel=\"lightbox-gallery-uGqeNroc\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-4202\" src=\"http:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/acidente6-300x199.jpg\" alt=\"acidente6\" width=\"172\" height=\"114\" srcset=\"https:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/acidente6-300x199.jpg 300w, https:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/acidente6.jpg 554w\" sizes=\"auto, (max-width: 172px) 100vw, 172px\" \/><\/a>Um choque em cadeia, envolvendo tr\u00eas viaturas ligeiras, na Estrada Nacional 105, mais propriamente nos sem\u00e1foros da Valinha, em Polvoreira, provocou quatro feridos ligeiros, ao in\u00edcio da noite de hoje, dia 14.<br \/>\n\u00c0s 20:36 era dado o alerta, sendo imediatamente accionada uma ambul\u00e2ncia com tr\u00eas bombeiros pois havia a informa\u00e7\u00e3o da exist\u00eancia de apenas um ferido. No entanto e ap\u00f3s a ambul\u00e2ncia chegar ao local, constatou-se a exist\u00eancia de mais tr\u00eas feridos ligeiros pelo que foi accionado mais duas ambul\u00e2ncias e cinco bombeiros.<\/p>\n<p style=\"text-align: justify;\">As v\u00edtimas, todas do sexo feminino e com 15, 36, 38 e 62 anos, ap\u00f3s estabilizadas no local foram transportadas para o Centro Hospitalar Alto Ave &#8211; Unidade de Guimar\u00e3es. No local esteve ainda a PSP que condicionou o tr\u00e2nsito naquela estrada nacional durante as opera\u00e7\u00f5es de socorro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um choque em cadeia, envolvendo tr\u00eas viaturas ligeiras, na Estrada Nacional 105, mais propriamente nos sem\u00e1foros da Valinha, em Polvoreira, provocou quatro feridos ligeiros, ao in\u00edcio da noite de hoje, dia 14. \u00c0s 20:36 era dado o alerta, sendo imediatamente<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[9,18,34,184,47,38],"class_list":["post-6829","post","type-post","status-publish","format-standard","hentry","category-noticias-gerais","tag-acidente","tag-bombeiros-voluntarios-de-guimaraes","tag-colisao","tag-en-105","tag-feridos","tag-polvoreira"],"_links":{"self":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts\/6829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/comments?post=6829"}],"version-history":[{"count":2,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts\/6829\/revisions"}],"predecessor-version":[{"id":6831,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts\/6829\/revisions\/6831"}],"wp:attachment":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/media?parent=6829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/categories?post=6829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/tags?post=6829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}