{"id":8056,"date":"2018-09-28T09:18:11","date_gmt":"2018-09-28T08:18:11","guid":{"rendered":"http:\/\/www.bv-guimaraes.org\/site\/?p=8056"},"modified":"2018-09-28T09:18:11","modified_gmt":"2018-09-28T08:18:11","slug":"protocolo-de-cooperacao-entre-a-associacao-humanitaria-dos-bombeiros-voluntarios-de-guimaraes-e-a-uniao-de-freguesias-de-selho-s-lourenco-e-gominhaes","status":"publish","type":"post","link":"https:\/\/www.bv-guimaraes.org\/site\/protocolo-de-cooperacao-entre-a-associacao-humanitaria-dos-bombeiros-voluntarios-de-guimaraes-e-a-uniao-de-freguesias-de-selho-s-lourenco-e-gominhaes\/","title":{"rendered":"Protocolo de Coopera\u00e7\u00e3o entre a Associa\u00e7\u00e3o Humanit\u00e1ria dos Bombeiros Volunt\u00e1rios de Guimar\u00e3es e a Uni\u00e3o de Freguesias de Selho S. Louren\u00e7o e Gominh\u00e3es"},"content":{"rendered":"<p><!--more--><\/p>\n<p>A Direc\u00e7\u00e3o, Comando e Corpo Activo de Bombeiros, n\u00e3o pode deixar de endere\u00e7ar os maiores agradecimentos ao Presidente Daniel Oliveira e restantes membros do executivo pela assinatura deste protocolo que, com certeza, ir\u00e1 contribuir para um melhor desempenho dos nossos bombeiros no socorro \u00e0 popula\u00e7\u00e3o que servimos.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-8057\" src=\"http:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/IMG_2945-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/IMG_2945-300x225.jpg 300w, https:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/IMG_2945-768x576.jpg 768w, https:\/\/www.bv-guimaraes.org\/site\/wp-content\/uploads\/IMG_2945.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8056","post","type-post","status-publish","format-standard","hentry","category-destaques"],"_links":{"self":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts\/8056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/comments?post=8056"}],"version-history":[{"count":1,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts\/8056\/revisions"}],"predecessor-version":[{"id":8058,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/posts\/8056\/revisions\/8058"}],"wp:attachment":[{"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/media?parent=8056"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/categories?post=8056"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bv-guimaraes.org\/site\/wp-json\/wp\/v2\/tags?post=8056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}